{"id":4146,"date":"2019-01-29T10:21:39","date_gmt":"2019-01-29T10:21:39","guid":{"rendered":"https:\/\/www.igj-italia.it\/nuovo\/shop\/reagente-per-testare-loro-21-kt\/"},"modified":"2019-04-24T09:34:24","modified_gmt":"2019-04-24T09:34:24","slug":"reagente-per-testare-loro-21-kt","status":"publish","type":"product","link":"https:\/\/www.igj-italia.it\/en\/acid-reagents\/reagente-per-testare-loro-21-kt\/","title":{"rendered":"Reagente per testare l&#8217;oro 21 kt"},"content":{"rendered":"<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\"><em><strong>I t a l i a n o\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.listeragent.com\/immagini\/flag_ita.gif\" alt=\"\" width=\"30\" height=\"22\" \/><\/strong><\/em><\/span><\/p>\n<blockquote dir=\"ltr\">\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\"><strong>ACIDO REAGENTE<\/strong><\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\"><strong>Per testare l&#8217;oro 21 kt (916 millesimi)<\/strong><\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">Quantit\u00e0 : 14cc<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">E&#8217; consigliato l&#8217;utilizzo con pietra di paragone,<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">in mancanza di questa<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">potrete mettere una goccia di acido sull&#8217;oggetto.<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">Se il vostro oggetto, nel punto dove avete messo l&#8217;acido\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">frigge non \u00e8 oro.<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">USARE CON LE DOVUTE PRECAUZIONI<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\">Ricevuta Fiscale<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt; color: #003300;\"><strong>NUOVO<\/strong><\/span><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>I t a l i a n o\u00a0 ACIDO REAGENTE Per testare l&#8217;oro 21 kt (916 millesimi) Quantit\u00e0 : 14cc E&#8217; consigliato l&#8217;utilizzo con pietra di paragone, in mancanza di questa potrete mettere una goccia di acido sull&#8217;oggetto. Se il vostro oggetto, nel punto dove avete messo l&#8217;acido\u00a0 frigge non \u00e8 oro. USARE CON LE [&hellip;]<\/p>\n","protected":false},"featured_media":4142,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[170],"product_tag":[],"class_list":["post-4146","product","type-product","status-publish","has-post-thumbnail","product_cat-acid-reagents","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/product\/4146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/media\/4142"}],"wp:attachment":[{"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/media?parent=4146"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/product_brand?post=4146"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/product_cat?post=4146"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.igj-italia.it\/en\/wp-json\/wp\/v2\/product_tag?post=4146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}